{"id":6597,"date":"2014-04-27T00:22:22","date_gmt":"2014-04-26T22:22:22","guid":{"rendered":"http:\/\/www.palentino.es\/blog\/?p=6597"},"modified":"2014-04-27T14:56:18","modified_gmt":"2014-04-27T12:56:18","slug":"aspectos-legales-a-considerar-en-una-web-futuro-ficheros-y-utilidades","status":"publish","type":"post","link":"https:\/\/www.palentino.es\/blog\/aspectos-legales-a-considerar-en-una-web-futuro-ficheros-y-utilidades\/","title":{"rendered":"Aspectos legales a considerar en una web. Futuro, ficheros y utilidades."},"content":{"rendered":"<div id=\"palen-689159767\" class=\"palen-antes-del-contenido palen-entity-placement\"><div class=\"palen-adlabel\">Anuncios<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-2815317153396146\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:inline-block;width:300px;height:250px;\" \ndata-ad-client=\"ca-pub-2815317153396146\" \ndata-ad-slot=\"4593837716\"><\/ins> \n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><p style=\"text-align: justify;\"><span style=\"color: #333333;\">En esta entrada voy a comentaros las acciones necesarias que se deben efectuar para que <strong>nuestro sitio web cumpla con la normativa legal vigente<\/strong>. Tambi\u00e9n expondr\u00e9 una serie de cuestiones que afectar\u00e1n en breve a los websites que se encarguen de realizar B2B \u00f3 B2C (negocio en Internet) y al final os dejar\u00e9 una serie de ficheros de f\u00e1cil incorporaci\u00f3n para cumplir <strong>la nueva ley de cookies<\/strong>, tanto para websites normales como enlaces a <strong>plugins<\/strong> si empleamos como CMS \u00a0la herramienta WordPress.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Intentar\u00e9 resumir de la forma sencilla los pasos, puesto que considero\u00a0no se acaba de explicar o entender bien. Veremos ideas de <strong>las secciones necesarias que tenemos que tener presentes en nuestra p\u00e1gina web<\/strong>. <\/span><\/p>\n<p style=\"text-align: justify;\">No obstante puedes contribuir en el <strong>Post\u00a0enviando tus sugerencias o cuestiones para mejorarlo<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Comencemos &#8230;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\"><!--more--><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Actualmente, cuando encargamos realizar a una empresa de dise\u00f1o web nuestro sitio o el de la empresa, es necesario tener en cuenta que <strong>no basta con que nos programen el sitio con las \u00faltimas tecnolog\u00edas existentes<\/strong> (HTML5, Css3, responsive, SEO,&#8230;), <strong>es preciso cumplir lo que dictamina la ley<\/strong>. Este aspecto<strong> se suele descuidar mucho<\/strong>,\u00a0y las consecuencias de la no adecuaci\u00f3n <strong>pueden ser econ\u00f3micamente graves<\/strong>.<\/span><\/p>\n<p><span style=\"color: #333333;\">Es preciso realizar una labor de consultor\u00eda con los clientes que deseen realizar una web e informar que todo\u00a0site que <strong>manipule informaci\u00f3n personal o realice operaciones econ\u00f3micas<\/strong> necesita\u00a0cumplir:<\/span><\/p>\n<p><span style=\"color: #333333;\"><strong style=\"color: #666666;\">LOPD:<\/strong>\u00a0Ley Org\u00e1nica de Protecci\u00f3n de Datos de Car\u00e1cter Personal (Ley Org\u00e1nica 15\/1999, de 13 de diciembre)<\/span><\/p>\n<p><span style=\"color: #333333;\"><strong style=\"color: #666666;\">LSSI:<\/strong>\u00a0Ley de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (Ley 34\/2002, de 11 de julio)<\/span><\/p>\n<p><span style=\"color: #333333;\"><strong>Ley de cookies:\u00a0<\/strong>La llamada Ley de Cookies no es una ley tal cual, sino que se trata del texto correspondiente al apartado segundo del art\u00edculo 22 de la\u00a0<a style=\"color: #48aede;\" href=\"http:\/\/boe.es\/buscar\/act.php?id=BOE-A-2002-13758\"><span style=\"color: #333333;\">Ley de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico<\/span><\/a>\u00a0(o LSSI), una vez modificado por el\u00a0<b style=\"color: #505050;\">Real Decreto-ley 13\/2012<\/b>\u00a0por el cual se transpon\u00edan una serie de directivas europeas.<\/span><\/p>\n<p><span style=\"color: #333333;\">\u00bfEsto en qu\u00e9 se traduce?, <strong>recomendaciones para la web<\/strong> (resumen).<\/span><\/p>\n<ol>\n<li><span style=\"color: #333333;\">Crear un apartado llamado <strong>Aviso legal<\/strong>. Suele estar siempre visible a pie de p\u00e1gina. \u00a0Ejemplo: <a href=\"http:\/\/www.palentino.es\/cookies\/aviso-legal-ejemplo.txt\" target=\"_blank\">aviso-legal-ejemplo.txt<\/a><\/span><\/li>\n<li><span style=\"color: #333333;\">Crear un apartado en la web <strong>Pol\u00edtica de privacidad<\/strong>, siempre visible a pie de p\u00e1gina. Ejemplo: <a href=\"http:\/\/www.palentino.es\/cookies\/politica-de-privacidad-ejemplo.txt\" target=\"_blank\">politica-de-privacidad-ejemplo.txt<\/a><\/span><\/li>\n<li><span style=\"color: #333333;\">Crear un apartado en todo formulario llamado\u00a0<strong>consentimiento informado<\/strong>. Y casillas de consentimiento y lectura. Ver ejemplo: <a href=\"http:\/\/www.palentino.es\/cookies\/consentimiento-informado-ejemplo.txt\" target=\"_blank\">consentimiento-informado-ejemplo.txt<br \/>\n<\/a>IMPORTANTE <span style=\"color: #800000;\">:Me gustar\u00eda hacer hincapi\u00e9 que este aspecto no se cumple mucho, he podido comprobar en muchos sites de empresas con formulario\u00a0web que s\u00f3lo pide un correo electr\u00f3nico,<\/span> <strong>la ausencia de este consentimiento,<\/strong> es obligatorio disponer del apartado consentimiento informado y su aceptaci\u00f3n. OJO<\/span><\/li>\n<li><span style=\"color: #333333;\">Crear un apartado<strong> Pol\u00edtica de cookies<\/strong>, y establecer ese aviso la primera vez que entramos en la web, para realizar la aceptaci\u00f3n. Ver ejemplo: <a href=\"http:\/\/www.palentino.es\/cookies\/politica-de-cookies-ejemplo.txt\" target=\"_blank\">politica-de-cookies-ejemplo.txt<\/a><\/span><\/li>\n<li><span style=\"color: #333333;\">Apartado <strong>condiciones de venta<\/strong>,\u00a0en caso de tienda virtual. Depende del tipo de negocio. (Cambios, devoluciones, gastos de env\u00edo, etc).<\/span><\/li>\n<\/ol>\n<p>Dejo los ejemplos en formato <strong>txt<\/strong> para insertar mejor en cualquier web.<\/p>\n<p><a href=\"http:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4154\" data-permalink=\"https:\/\/www.palentino.es\/blog\/trucos-para-el-sistema-que-te-pueden-ayudar\/barra-separadora-blog\/\" data-orig-file=\"https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg\" data-orig-size=\"641,3\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Barra-separadora-blog\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg\" class=\"aligncenter size-full wp-image-4154\" src=\"http:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg\" alt=\"Barra-separadora-blog\" width=\"641\" height=\"3\" srcset=\"https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg 641w, https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog-300x1.jpg 300w\" sizes=\"auto, (max-width: 641px) 100vw, 641px\" \/><\/a><\/p>\n<p><strong>Novedades y Futuro. La ley de Derechos del consumidor.<\/strong><\/p>\n<p>Os adelanto que a partir<strong> del 13 de Junio del 2014<\/strong> \u00a0comenzar\u00e1 a aplicarse <strong>La nueva Ley de Derechos del consumidor<\/strong>. \u00a0Debido al aumento en la venta de productos digitales, la UE ha considerado\u00a0conveniente regular este mercado en auge para proteger los derechos de los consumidores. Los productos digitales difieren de los productos f\u00edsicos en cuanto a su regulaci\u00f3n.<\/p>\n<p>Por lo tanto, con la directiva <strong>Europea 2011\/83\/UE<\/strong> sobre derechos de los consumidores se regular\u00e1 la necesidad de que el consumidor o internauta <strong>acepte de manera expresa las condiciones de venta<\/strong> (por mail por ejemplo). Es necesario indicar que estamos de acuerdo con el precio final y con los derechos de utilizaci\u00f3n. Por lo que podemos entender <strong>a partir de junio, las tiendas on-line tendr\u00e1n que adaptarse para ofrecer a los usuarios informaci\u00f3n sobre el precio final, y una renuncia a la devoluci\u00f3n de contenido<\/strong>. Las web de venta online tendr\u00e1n que adaptar sus p\u00e1ginas para mostrar esta informaci\u00f3n, indicando de alguna manera que el consumidor esta conforme con las condiciones de compra.<\/p>\n<p>Aqu\u00ed entra en juego un nuevo concepto: &#8220;<strong>El derecho de desistimiento<\/strong>&#8220;.<br \/>\nDespu\u00e9s de comenzar\u00a0la descarga de un archivo digital, no se podr\u00e1 devolverle como si fuese un producto f\u00edsico.&#8221; El consumidor tendr\u00e1 que cumplimentar un formulario online aceptando la renuncia a la devoluci\u00f3n del contenido.&#8221;<\/p>\n<p>En resumen, con la nueva ley las tiendas en Internet necesitar\u00e1n asegurar que los consumidores hayan dado su consentimiento expreso para ejecutar el contrato y el comprobante.<\/p>\n<p><a href=\"http:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4154\" data-permalink=\"https:\/\/www.palentino.es\/blog\/trucos-para-el-sistema-que-te-pueden-ayudar\/barra-separadora-blog\/\" data-orig-file=\"https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg\" data-orig-size=\"641,3\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Barra-separadora-blog\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg\" class=\"aligncenter size-full wp-image-4154\" src=\"http:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg\" alt=\"Barra-separadora-blog\" width=\"641\" height=\"3\" srcset=\"https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg 641w, https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog-300x1.jpg 300w\" sizes=\"auto, (max-width: 641px) 100vw, 641px\" \/><\/a><\/p>\n<p><strong>Ficheros para cumplir la pol\u00edtica de cookies.<\/strong><\/p>\n<p>Plugin para wordpress:\u00a0<a href=\"https:\/\/wordpress.org\/plugins\/asesor-cookies-para-la-ley-en-espana\/\" target=\"_blank\">https:\/\/wordpress.org\/plugins\/asesor-cookies-para-la-ley-en-espana\/<\/a><\/p>\n<p><span style=\"color: #800000;\">Ficheros para web normal:<\/span><\/p>\n<p>Os dejo un archivo .rar y dentro las \u00a0instrucciones para incorporar la pol\u00edtica cookies en cualquier web realizada a mano. \ud83d\ude42<\/p>\n<p>Lo he creado de forma muy sencilla y f\u00e1cil de incorporar. Posee estilos para explorer y otros navegadores.<\/p>\n<p><a href=\"http:\/\/www.palentino.es\/cookies\/cookies-palentino.rar\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6564\" data-permalink=\"https:\/\/www.palentino.es\/blog\/pal-ssd-utilidad-para-alargar-la-vida-y-aumentar-la-velocidad-de-la-unidad-ssd\/winrar\/\" data-orig-file=\"https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2014\/04\/winrar.jpg\" data-orig-size=\"90,90\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"winrar\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2014\/04\/winrar.jpg\" class=\"aligncenter size-full wp-image-6564\" src=\"http:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2014\/04\/winrar.jpg\" alt=\"winrar\" width=\"90\" height=\"90\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Ejemplo de la pagina demo:<\/p>\n<p>&nbsp;<\/p>\n<pre lang=\"html\">Ejemplo<script src=\"js\/cookies.js\"><\/script><\/pre>\n<div>Utilizamos cookies propias y de terceros, para realizar el an\u00e1lisis de la navegaci\u00f3n de los usuarios. Si contin\u00faas navegando, consideramos que aceptas su uso. Puedes cambiar la configuraci\u00f3n u obtener <a href=\"enlaceleycookies.html\" target=\"_blank\">m\u00e1s informaci\u00f3n.<\/a> | <a><b>OK<\/b><\/a><\/div>\n<div id=\"barraaceptacion\">\n<p>&nbsp;<\/p>\n<\/div>\n<p><script src=\"js\/cookies-debajo.js\"><\/script><\/p>\n<p>&nbsp;<\/p>\n<p>Espero que os sirva.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4154\" data-permalink=\"https:\/\/www.palentino.es\/blog\/trucos-para-el-sistema-que-te-pueden-ayudar\/barra-separadora-blog\/\" data-orig-file=\"https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg\" data-orig-size=\"641,3\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Barra-separadora-blog\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg\" class=\"aligncenter size-full wp-image-4154\" src=\"http:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg\" alt=\"Barra-separadora-blog\" width=\"641\" height=\"3\" srcset=\"https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog.jpg 641w, https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2013\/04\/Barra-separadora-blog-300x1.jpg 300w\" sizes=\"auto, (max-width: 641px) 100vw, 641px\" \/><\/a><\/p>\n<p><strong>Anexos<\/strong>:<\/p>\n<p><span style=\"color: #333399;\"><a style=\"color: #48aede;\" href=\"http:\/\/www.agpd.es\/portalwebAGPD\/canaldocumentacion\/publicaciones\/common\/Guias\/Guia_Cookies.pdf\" target=\"_blank\"><span style=\"color: #333399;\">Gu\u00eda sobre el uso de las cookies (AGPD)<\/span><\/a><\/span><\/p>\n<p><span style=\"color: #333399;\"><a style=\"color: #48aede;\" href=\"http:\/\/boe.es\/buscar\/act.php?id=BOE-A-2002-13758\"><span style=\"color: #333399;\">Ley de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico<\/span><\/a>\u00a0<\/span><\/p>\n<p>Enlace a la\u00a0<span style=\"color: #505050;\">\u00a0<\/span><span style=\"color: #333399;\"><a style=\"color: #48aede;\" href=\"http:\/\/www.agpd.es\/portalwebAGPD\/index-ides-idphp.php\" target=\"_blank\"><span style=\"color: #333399;\">Agencia Espa\u00f1ola de Protecci\u00f3n de Datos (AGDP)<\/span><\/a><\/span><\/p>\n<p>Enlace a la ley\u00a0<strong><a href=\"http:\/\/www.boe.es\/boe\/dias\/1999\/12\/14\/pdfs\/A43088-43099.pdf\" target=\"_blank\">LOPD<\/a>\u00a0(pdf)<\/strong><\/p>\n<div id=\"palen-2860364632\" class=\"palen-despues-del-contenido palen-entity-placement\"><div class=\"palen-adlabel\">Anuncios<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-2815317153396146\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-2815317153396146\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\" data-full-width-responsive=\"true\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>En esta entrada voy a comentaros las acciones necesarias que se deben efectuar para que nuestro sitio web cumpla con la normativa legal vigente. Tambi\u00e9n expondr\u00e9 una serie de cuestiones que afectar\u00e1n en breve a los websites que se encarguen de realizar B2B \u00f3 B2C (negocio en Internet) y al final os dejar\u00e9 una serie de ficheros de f\u00e1cil incorporaci\u00f3n para cumplir la nueva ley de cookies, tanto para websites normales como enlaces a plugins si empleamos como CMS \u00a0la herramienta WordPress. Intentar\u00e9 resumir de la forma sencilla los pasos, puesto que considero\u00a0no se acaba de explicar o entender bien. Veremos ideas de las secciones necesarias que tenemos que tener presentes en nuestra p\u00e1gina web. No obstante puedes contribuir en el Post\u00a0enviando tus sugerencias o cuestiones para mejorarlo. Comencemos &#8230;<\/p>\n","protected":false},"author":1,"featured_media":6603,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[14],"tags":[551,549,547,548,228,552,550],"class_list":["post-6597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-varios","tag-cookies","tag-legal","tag-lopd","tag-lssi","tag-palentino","tag-script","tag-website"],"views":3243,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.palentino.es\/blog\/wp-content\/uploads\/2014\/04\/aspectos-legales.jpg","jetpack_shortlink":"https:\/\/wp.me\/p2ECph-1Ip","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.palentino.es\/blog\/wp-json\/wp\/v2\/posts\/6597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palentino.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palentino.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palentino.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palentino.es\/blog\/wp-json\/wp\/v2\/comments?post=6597"}],"version-history":[{"count":24,"href":"https:\/\/www.palentino.es\/blog\/wp-json\/wp\/v2\/posts\/6597\/revisions"}],"predecessor-version":[{"id":6623,"href":"https:\/\/www.palentino.es\/blog\/wp-json\/wp\/v2\/posts\/6597\/revisions\/6623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.palentino.es\/blog\/wp-json\/wp\/v2\/media\/6603"}],"wp:attachment":[{"href":"https:\/\/www.palentino.es\/blog\/wp-json\/wp\/v2\/media?parent=6597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palentino.es\/blog\/wp-json\/wp\/v2\/categories?post=6597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palentino.es\/blog\/wp-json\/wp\/v2\/tags?post=6597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}